{"id":2833,"date":"2020-12-02T21:17:05","date_gmt":"2020-12-02T21:17:05","guid":{"rendered":"https:\/\/donmelchor.com\/?p=2833"},"modified":"2020-12-02T21:17:05","modified_gmt":"2020-12-02T21:17:05","slug":"enrique-tirado-presento-la-cosecha-2018-de-don-melchor-al-mercado-brasileno","status":"publish","type":"post","link":"https:\/\/donmelchor.com\/pt-pt\/enrique-tirado-presento-la-cosecha-2018-de-don-melchor-al-mercado-brasileno\/","title":{"rendered":"Enrique Tirado apresenta a safra 2018 do Don Melchor para o mercado brasileiro"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[38],"tags":[],"class_list":["post-2833","post","type-post","status-publish","format-standard","hentry","category-events-pt-pt"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Enrique Tirado apresenta a safra 2018 do Don Melchor para o mercado brasileiro - Don Melchor<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/donmelchor.com\/pt-pt\/enrique-tirado-presento-la-cosecha-2018-de-don-melchor-al-mercado-brasileno\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Enrique Tirado apresenta a safra 2018 do Don Melchor para o mercado brasileiro - Don Melchor\" \/>\n<meta property=\"og:url\" content=\"https:\/\/donmelchor.com\/pt-pt\/enrique-tirado-presento-la-cosecha-2018-de-don-melchor-al-mercado-brasileno\/\" \/>\n<meta property=\"og:site_name\" content=\"Don Melchor\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-02T21:17:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/donmelchor.com\/wp-content\/uploads\/2023\/11\/descarga.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"250\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Don Melchor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Don Melchor\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Enrique Tirado apresenta a safra 2018 do Don Melchor para o mercado brasileiro - Don Melchor","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/donmelchor.com\/pt-pt\/enrique-tirado-presento-la-cosecha-2018-de-don-melchor-al-mercado-brasileno\/","og_locale":"pt_PT","og_type":"article","og_title":"Enrique Tirado apresenta a safra 2018 do Don Melchor para o mercado brasileiro - Don Melchor","og_url":"https:\/\/donmelchor.com\/pt-pt\/enrique-tirado-presento-la-cosecha-2018-de-don-melchor-al-mercado-brasileno\/","og_site_name":"Don Melchor","article_published_time":"2020-12-02T21:17:05+00:00","og_image":[{"width":250,"height":250,"url":"https:\/\/donmelchor.com\/wp-content\/uploads\/2023\/11\/descarga.jpg","type":"image\/jpeg"}],"author":"Don Melchor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Don Melchor"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/donmelchor.com\/pt-pt\/enrique-tirado-presento-la-cosecha-2018-de-don-melchor-al-mercado-brasileno\/#article","isPartOf":{"@id":"https:\/\/donmelchor.com\/pt-pt\/enrique-tirado-presento-la-cosecha-2018-de-don-melchor-al-mercado-brasileno\/"},"author":{"name":"Don Melchor","@id":"https:\/\/donmelchor.com\/#\/schema\/person\/968ea15c854bb0d3cc423e1b7d5eef65"},"headline":"Enrique Tirado apresenta a safra 2018 do Don Melchor para o mercado brasileiro","datePublished":"2020-12-02T21:17:05+00:00","mainEntityOfPage":{"@id":"https:\/\/donmelchor.com\/pt-pt\/enrique-tirado-presento-la-cosecha-2018-de-don-melchor-al-mercado-brasileno\/"},"wordCount":12,"articleSection":["Eventos"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/donmelchor.com\/pt-pt\/enrique-tirado-presento-la-cosecha-2018-de-don-melchor-al-mercado-brasileno\/","url":"https:\/\/donmelchor.com\/pt-pt\/enrique-tirado-presento-la-cosecha-2018-de-don-melchor-al-mercado-brasileno\/","name":"Enrique Tirado apresenta a safra 2018 do Don Melchor para o mercado brasileiro - Don Melchor","isPartOf":{"@id":"https:\/\/donmelchor.com\/#website"},"datePublished":"2020-12-02T21:17:05+00:00","author":{"@id":"https:\/\/donmelchor.com\/#\/schema\/person\/968ea15c854bb0d3cc423e1b7d5eef65"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/donmelchor.com\/pt-pt\/enrique-tirado-presento-la-cosecha-2018-de-don-melchor-al-mercado-brasileno\/"]}]},{"@type":"WebSite","@id":"https:\/\/donmelchor.com\/#website","url":"https:\/\/donmelchor.com\/","name":"Don Melchor","description":"El Cabernet Sauvignon \u00edcono de Puente Alto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/donmelchor.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/donmelchor.com\/#\/schema\/person\/968ea15c854bb0d3cc423e1b7d5eef65","name":"Don Melchor","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/donmelchor.com\/wp-content\/litespeed\/avatar\/699027e340e35c45ed075092c3b24644.jpg?ver=1778577423","url":"https:\/\/donmelchor.com\/wp-content\/litespeed\/avatar\/699027e340e35c45ed075092c3b24644.jpg?ver=1778577423","contentUrl":"https:\/\/donmelchor.com\/wp-content\/litespeed\/avatar\/699027e340e35c45ed075092c3b24644.jpg?ver=1778577423","caption":"Don Melchor"},"sameAs":["http:\/\/para%20asociar%20contenido%20de%20usuarios%20que%20se%20borren"],"url":"https:\/\/donmelchor.com\/pt-pt\/author\/dummywant-cl\/"}]}},"_links":{"self":[{"href":"https:\/\/donmelchor.com\/pt-pt\/wp-json\/wp\/v2\/posts\/2833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/donmelchor.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/donmelchor.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/donmelchor.com\/pt-pt\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/donmelchor.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=2833"}],"version-history":[{"count":2,"href":"https:\/\/donmelchor.com\/pt-pt\/wp-json\/wp\/v2\/posts\/2833\/revisions"}],"predecessor-version":[{"id":2835,"href":"https:\/\/donmelchor.com\/pt-pt\/wp-json\/wp\/v2\/posts\/2833\/revisions\/2835"}],"wp:attachment":[{"href":"https:\/\/donmelchor.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=2833"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/donmelchor.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=2833"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/donmelchor.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=2833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}